{"id":7586,"date":"2021-11-03T12:28:31","date_gmt":"2021-11-03T15:28:31","guid":{"rendered":"http:\/\/sh-pro102.teste.website\/~trifas26\/?page_id=7586"},"modified":"2026-01-28T00:21:45","modified_gmt":"2026-01-28T03:21:45","slug":"categoria-de-condutores","status":"publish","type":"page","link":"https:\/\/trifasica.com.br\/es\/categoria-de-condutores\/","title":{"rendered":"Categor\u00eda de conductor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7586\" class=\"elementor elementor-7586\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb178a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb178a3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a83793e&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ae4931\" data-id=\"9ae4931\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20bd499 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"20bd499\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;c31e321&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1ef4d1f\" data-id=\"1ef4d1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913cd65 elementor-widget elementor-widget-heading\" data-id=\"913cd65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Categoria de Condutores<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-409fe81 elementor-widget elementor-widget-text-editor\" data-id=\"409fe81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Condutor el\u00e9trico \u00e9 qualquer material que ofere\u00e7a baixa resist\u00eancia el\u00e9trica, facilitando a passagem da corrente el\u00e9trica.<\/p><p>A escolha do tipo de condutor depende das caracter\u00edsticas de onde ele ser\u00e1 instalado, por\u00e9m em sua grande maioria, quando falamos em instala\u00e7\u00f5es el\u00e9tricas, falamos de cabos de cobre, pelas suas caracter\u00edsticas de resist\u00eancia \u00e0 corros\u00e3o e \u00e0 deforma\u00e7\u00e3o, al\u00e9m de ser muito male\u00e1vel.<\/p><p>Na Trif\u00e1sica El\u00e9trica voc\u00ea encontra fios e cabos de cobre duro e meio duro, com ou sem cobertura protetora, para instala\u00e7\u00f5es a\u00e9reas, transmiss\u00e3o e distribui\u00e7\u00e3o de energia el\u00e9trica e sistemas, adequados \u00e0 NBR 6524.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf85e49 elementor-widget elementor-widget-jet-woo-products\" data-id=\"cf85e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;6&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;2&quot;}\" data-widget_type=\"jet-woo-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-woo-products jet-woo-builder\"><div class=\"jet-woo-products jet-woo-products--preset-1 col-row  jet-equal-cols\" data-mobile-hover=\"\" >\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6834\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabo-4-vias-blindado\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/cabo-4-vias-blindado.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabo-4-vias-blindado\/\">Cabo 4 Vias Blindado<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6836\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabos-de-cobre-isolado-750-vca-06-1-kv\/\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/cabos-de-cobre-isolado.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabos-de-cobre-isolado-750-vca-06-1-kv\/\">Cabos de Cobre Isolado 750 VCA 0,6\/1 Kv<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6835\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabos-de-cobre-isolado-87-15kv12-20kv15-25kv20-35kv\/\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/cobre-isolado.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/cabos-de-cobre-isolado-87-15kv12-20kv15-25kv20-35kv\/\">Cabos de Cobre Isolado 8,7\/15kV12\/20KV15\/25KV20\/35KV<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6837\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/conector-split-bolt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/conector-split-bolt.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/conector-split-bolt\/\">Conector Split Bolt<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6838\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/luva-emenda-a-compressao\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/luva-emenda-a-compressao.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/luva-emenda-a-compressao\/\">Luva Emenda a Compress\u00e3o<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6840\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-compressao\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/terminal-compressao.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-compressao\/\">Terminal Compress\u00e3o<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"6839\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-pressao-reforcado\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/terminal-pressao-reforcado.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-pressao-reforcado\/\">Terminal Press\u00e3o Refor\u00e7ado<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"9321\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-5\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Unidut-Conico-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-5\/\">Unidut C\u00f4nico 5&#8243;<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"9324\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-6\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Unidut-Conico-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-6\/\">Unidut C\u00f4nico 6&#8243;<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"9326\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-reto-5\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Unidut-Reto-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-reto-5\/\">Unidut Reto 5&#8243;<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product\" data-product-id=\"9332\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-reto-6\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Unidut-Reto-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-reto-6\/\">Unidut Reto 6&#8243;<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8778299 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8778299\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;2b9e695&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68c3a18\" data-id=\"68c3a18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4b12b6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f4b12b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e54a8fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e54a8fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;2b9e695&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef38723\" data-id=\"ef38723\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b18247 elementor-widget elementor-widget-heading\" data-id=\"4b18247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conhe\u00e7a outros produtos da Trif\u00e1sica El\u00e9trica<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0377e1a elementor-widget elementor-widget-jet-woo-products\" data-id=\"0377e1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;6&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between_slides&quot;:10}\" data-widget_type=\"jet-woo-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-woo-products jet-woo-builder\"><div class=\"jet-woo-carousel horizontal swiper\" data-slider_options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerGroup&quot;:1,&quot;simulateTouch&quot;:true,&quot;loop&quot;:true,&quot;freeMode&quot;:false,&quot;centeredSlides&quot;:false,&quot;speed&quot;:500,&quot;paginationEnable&quot;:false,&quot;navigationEnable&quot;:true,&quot;autoplay&quot;:{&quot;delay&quot;:5000,&quot;disableOnInteraction&quot;:true}}\" dir=\"ltr\"> <div class=\"jet-woo-products jet-woo-products--preset-1 swiper-wrapper  jet-equal-cols\" data-mobile-hover=\"\" >\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"14098\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-pextron-pcpt-4\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2025\/05\/pextron-pcpt-4.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-pextron-pcpt-4\/\">Rel\u00e9 Pextron PCPT 4<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"9375\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/transformador-de-potencia-a-oleo-300kva-15kv-220-127vca\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/04\/transformador-de-potencia-a-oleo.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/transformador-de-potencia-a-oleo-300kva-15kv-220-127vca\/\">Transformador de Pot\u00eancia a \u00d3leo 300kVA\/ 15kV &#8211; 220\/127VCA<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"8599\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/para-raio-polimerico-15kv-10ka21kv-10ka\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2023\/11\/Para-Raio-Polimerico.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/para-raio-polimerico-15kv-10ka21kv-10ka\/\">Para-Raio Polim\u00e9rico 21kV 10ka<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"6851\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/disjuntor-tavrida-lateral\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1023\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2021\/10\/disjuntor-tavrida-lateral.png\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/disjuntor-tavrida-lateral\/\">Disjuntor Tavrida Lateral<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"14091\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-pextron-urpe-7104t\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2025\/05\/pextron-7104T.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-pextron-urpe-7104t\/\">Rel\u00e9 Pextron URPE 7104T<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"9306\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/punho-de-manobra-kirk-yale-esquerdo\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Punh-de-Manobra-Kirk-Yale-Esquerdo.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/punho-de-manobra-kirk-yale-esquerdo\/\">Punho de Manobra Kirk Yale Esquerdo<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"14117\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-schneider-easergy-p5\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2025\/05\/schneider-p5.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/rele-schneider-easergy-p5\/\">Rel\u00e9 Schneider Easergy P5<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"9324\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-6\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/Unidut-Conico-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/unidut-conico-6\/\">Unidut C\u00f4nico 6&#8243;<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"8583\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-desconectavel-de-media-tensao-120-240mm-36-kv\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/terminal-desconectavel-35-kV-400mm-rstl-6951-br.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-desconectavel-de-media-tensao-120-240mm-36-kv\/\">Terminal Desconect\u00e1vel 35 KV\/120-240mm RSTI-6853-BR<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"8581\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-desconectavel-de-media-tensao-25mm-15-25-kv-loadbreak\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/terminal-desconectavel-35-kV-400mm-rstl-6951-br.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/terminal-desconectavel-de-media-tensao-25mm-15-25-kv-loadbreak\/\">Terminal Desconect\u00e1vel TDC 200A, 25 kV\/25mm LOADBREAK<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"6815\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/conjunto-para-aterramento-temporario-15-kv\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2024\/03\/conjunto-para-aterramento-temp-1.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/conjunto-para-aterramento-temporario-15-kv\/\">Conjunto para Aterramento Tempor\u00e1rio 15 kV<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div>\n<div class=\"jet-woo-products__item jet-woo-builder-product swiper-slide\" data-product-id=\"8606\">\n\t<div class=\"jet-woo-products__inner-box\"  >\n\t\t\n<div class=\"jet-woo-product-thumbnail\">\n\t\n\t<a href=\"https:\/\/trifasica.com.br\/es\/producto\/isolador-epoxi-36kv\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/trifasica.com.br\/wp-content\/uploads\/2023\/11\/Isolador-Pedestal-Epoxi.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t<div class=\"jet-woo-product-img-overlay\"><\/div>\n\n\t\n\t<\/div><h5 class=\"jet-woo-product-title\"><a href=\"https:\/\/trifasica.com.br\/es\/producto\/isolador-epoxi-36kv\/\">Isolador Pedestal Epoxi 36kV (c\/ prensa fio)<\/a><\/h5>\n<div class=\"jet-woo-products-cqw-wrapper\">\n\t<\/div>\t<\/div>\n\n\t<\/div><\/div>\n  <div class=\"prev-arrow jet-swiper-button-prev jet-arrow\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><\/div> <div class=\"next-arrow jet-swiper-button-next jet-arrow\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div> <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Categoria de Condutores Condutor el\u00e9trico \u00e9 qualquer material que ofere\u00e7a baixa resist\u00eancia el\u00e9trica, facilitando a passagem da corrente el\u00e9trica. A escolha do tipo de condutor depende das caracter\u00edsticas de onde ele ser\u00e1 instalado, por\u00e9m em sua grande maioria, quando falamos em instala\u00e7\u00f5es el\u00e9tricas, falamos de cabos de cobre, pelas suas caracter\u00edsticas de resist\u00eancia \u00e0 corros\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-7586","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/pages\/7586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/comments?post=7586"}],"version-history":[{"count":0,"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/pages\/7586\/revisions"}],"wp:attachment":[{"href":"https:\/\/trifasica.com.br\/es\/wp-json\/wp\/v2\/media?parent=7586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}